{"id":26,"count":1,"description":"","link":"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/","name":"Recrutamento","slug":"recrutamento","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de Recrutamento | Blog do Candidato.pt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Recrutamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Candidato.pt\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.candidato.pt\/blog\/wp-content\/uploads\/2025\/06\/logo-rectangulo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/\",\"url\":\"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/\",\"name\":\"Arquivo de Recrutamento | Blog do Candidato.pt\",\"isPartOf\":{\"@id\":\"https:\/\/www.candidato.pt\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.candidato.pt\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recrutamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.candidato.pt\/blog\/#website\",\"url\":\"https:\/\/www.candidato.pt\/blog\/\",\"name\":\"Blog do Candidato.pt\",\"description\":\"Conectamos profissionais talentosos \u00e0s melhores empresas de Portugal e do mundo\",\"publisher\":{\"@id\":\"https:\/\/www.candidato.pt\/blog\/#organization\"},\"alternateName\":\"Blog do Candidato.pt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.candidato.pt\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.candidato.pt\/blog\/#organization\",\"name\":\"Blog do Candidato.pt\",\"url\":\"https:\/\/www.candidato.pt\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.candidato.pt\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.candidato.pt\/wp-content\/uploads\/2025\/05\/cropped-icon-mobile.png\",\"contentUrl\":\"https:\/\/blog.candidato.pt\/wp-content\/uploads\/2025\/05\/cropped-icon-mobile.png\",\"width\":512,\"height\":512,\"caption\":\"Blog do Candidato.pt\"},\"image\":{\"@id\":\"https:\/\/www.candidato.pt\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/candidato.pt\/\"],\"description\":\"Conectamos profissionais talentosos \u00e0s melhores empresas de Portugal e do mundo.\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arquivo de Recrutamento | Blog do Candidato.pt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/","og_locale":"pt_PT","og_type":"article","og_title":"Arquivo de Recrutamento","og_url":"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/","og_site_name":"Blog do Candidato.pt","og_image":[{"width":1200,"height":849,"url":"https:\/\/www.candidato.pt\/blog\/wp-content\/uploads\/2025\/06\/logo-rectangulo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/","url":"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/","name":"Arquivo de Recrutamento | Blog do Candidato.pt","isPartOf":{"@id":"https:\/\/www.candidato.pt\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.candidato.pt\/blog\/category\/recrutamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.candidato.pt\/blog\/"},{"@type":"ListItem","position":2,"name":"Recrutamento"}]},{"@type":"WebSite","@id":"https:\/\/www.candidato.pt\/blog\/#website","url":"https:\/\/www.candidato.pt\/blog\/","name":"Blog do Candidato.pt","description":"Conectamos profissionais talentosos \u00e0s melhores empresas de Portugal e do mundo","publisher":{"@id":"https:\/\/www.candidato.pt\/blog\/#organization"},"alternateName":"Blog do Candidato.pt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.candidato.pt\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.candidato.pt\/blog\/#organization","name":"Blog do Candidato.pt","url":"https:\/\/www.candidato.pt\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.candidato.pt\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blog.candidato.pt\/wp-content\/uploads\/2025\/05\/cropped-icon-mobile.png","contentUrl":"https:\/\/blog.candidato.pt\/wp-content\/uploads\/2025\/05\/cropped-icon-mobile.png","width":512,"height":512,"caption":"Blog do Candidato.pt"},"image":{"@id":"https:\/\/www.candidato.pt\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/candidato.pt\/"],"description":"Conectamos profissionais talentosos \u00e0s melhores empresas de Portugal e do mundo.","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/www.candidato.pt\/blog\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.candidato.pt\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.candidato.pt\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.candidato.pt\/blog\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}